{"id":311,"date":"2022-02-18T13:22:36","date_gmt":"2022-02-18T11:22:36","guid":{"rendered":"https:\/\/karusele.com\/?post_type=product&#038;p=311"},"modified":"2023-01-23T14:15:26","modified_gmt":"2023-01-23T12:15:26","slug":"lakstai","status":"publish","type":"product","link":"https:\/\/karusele.com\/en\/produktai\/lakstai\/","title":{"rendered":"Stainless steel plates"},"content":{"rendered":"<p>Measurements of stainless steel plates:<\/p>\n<table class=\"btable\" border=\"0\" width=\"423\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td width=\"108\">\n<p align=\"center\"><strong>AISI 304<\/strong><\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\"><strong>2B + PVC<\/strong><\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\"><strong>Polished + PVC<\/strong><\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\"><strong>2B<\/strong><\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\"><strong>Weight Kg<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0.5 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">8<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0.5 x 1250 x 2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">12,5<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0.8 x 1250 x 2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">20,3<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0.9 x 1250 x 2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">22,5<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">16<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1 x 1250 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">20<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1 x 1250 x 2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">25<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1.5 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">25<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1.5 x 1250 x 2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">37,5<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1.5 x 1500 x 3000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">54<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">2 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">32<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">2 x 1250 x 2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">50,3<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">2 x 1500 x 3000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">72<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">3 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">49<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">3 x 1250 x 2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">75<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">3 x 1500 x 3000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">108<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">3.2 x 1500 x 3000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">115,2<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">3 x 1000 x 2000 rifl.<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">53,8<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">3 x 1250 x 2500 rifl.<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">77<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">4 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">64<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">4 x 1250 x 2500 k.v.<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">100,8<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">6 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">96<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">8 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">128<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\"><strong>AISI 316<\/strong><\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\"><strong>2B<\/strong><\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\"><strong>Polished +PVC<\/strong><\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\"><strong>2B<\/strong><\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\"><strong>Weight Kg<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0,5x1000x2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">8<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0,5x1250x2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">12,5<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1x1000x2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">16<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1x1250x2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">25<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">2x1000x2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">32<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">2x1250x2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">50,3<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">3x1000x2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">48<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">3x1250x2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">75<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\"><strong>AISI 430<\/strong><\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\"><strong>2B + PVC<\/strong><\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\"><strong>Polished + PVC<\/strong><\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\"><strong>2B<\/strong><\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\"><strong>Weight Kg<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0.5 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">8<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0.8 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">13<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0.8 x 1250 x 2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">20,3<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">16<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1 x 1250 x 2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">25<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1 x 1500 x 3000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">36<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1.5 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">25<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1.5 x 1250 x 2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">37,5<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">2 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">32<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">2 x 1250 x 2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">50,3<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"69\">\n<p align=\"center\">\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\"><strong>AISI 409<\/strong><\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\"><strong>2B + PVC<\/strong><\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\"><strong>Polished + PVC<\/strong><\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\"><strong>2B<\/strong><\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\"><strong>Weight Kg<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0.5 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">8<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0.8 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">13<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">16<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"69\">\n<p align=\"center\">\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\"><strong>AISI 321<\/strong><\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\"><strong>2B + PVC<\/strong><\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\"><strong>Polished + PVC<\/strong><\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\"><strong>2B<\/strong><\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\"><strong>Weight Kg<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0.5 x 1000 x 2000<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">8<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0.5 x 1250 x 2500<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">12,5<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"69\">\n<p align=\"center\">\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\"><strong>Non-standard<\/strong><\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\"><strong>2B + PVC<\/strong><\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\"><strong>Polished + PVC<\/strong><\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\"><strong>2B<\/strong><\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">0.8 x 1000 x 2000 (430)<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">12,8<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1 x 1000 x 1250 (430)<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">10<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1 x 1340 x 1940 (430)<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">21,2<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">1 x 1520 x 1980 (430)<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"69\">\n<p align=\"center\">20,8<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"108\">\n<p align=\"center\">2.5 x 1500 x 3000 (430)<\/p>\n<\/td>\n<td width=\"82\">\n<p align=\"center\">+<\/p>\n<\/td>\n<td width=\"70\">\n<p align=\"center\">\n<\/td>\n<td width=\"82\">\n<p align=\"center\">\n<\/td>\n<td width=\"69\">\n<p align=\"center\">90<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Polished+PVC  polished packed in PVC<\/p>\n<p>2b+PVC  mat packed in PVC<\/p>\n<p>2b  mat<\/p>","protected":false},"excerpt":{"rendered":"<p><span style=\"font-weight: 400;\">The surface of stainless steel plates can be processed in various ways: polished, grind, matte, raw. These products can be used in the dairy, meat, vegetable, beverage and other food industries. Stainless steel plate can be made from AISI 304 or AISI 316 metal. You can also buy decorative non-slip stainless steel plates from us.<\/span><\/p>\n<p><br style=\"font-weight: 400;\" \/><br style=\"font-weight: 400;\" \/><\/p>","protected":false},"featured_media":707,"template":"","meta":[],"product_brand":[],"product_cat":[50,17],"product_tag":[],"class_list":{"0":"post-311","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-lakstai","7":"product_cat-nerudijantis-plienas","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/karusele.com\/en\/wp-json\/wp\/v2\/product\/311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karusele.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/karusele.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/karusele.com\/en\/wp-json\/wp\/v2\/media\/707"}],"wp:attachment":[{"href":"https:\/\/karusele.com\/en\/wp-json\/wp\/v2\/media?parent=311"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/karusele.com\/en\/wp-json\/wp\/v2\/product_brand?post=311"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/karusele.com\/en\/wp-json\/wp\/v2\/product_cat?post=311"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/karusele.com\/en\/wp-json\/wp\/v2\/product_tag?post=311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}